{"id":5370,"count":3,"description":"","link":"https:\/\/www.stradadeiparchi.it\/en\/tag\/west-eagle\/","name":"west eagle","slug":"west-eagle","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>west eagle | Strada dei Parchi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stradadeiparchi.it\/en\/tag\/west-eagle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"west eagle | Strada dei Parchi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stradadeiparchi.it\/en\/tag\/west-eagle\/\" \/>\n<meta property=\"og:site_name\" content=\"Strada dei Parchi\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/en\\\/tag\\\/west-eagle\\\/\",\"url\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/en\\\/tag\\\/west-eagle\\\/\",\"name\":\"west eagle | Strada dei Parchi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/en\\\/tag\\\/west-eagle\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/en\\\/tag\\\/west-eagle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"west eagle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/#website\",\"url\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/\",\"name\":\"Strada dei Parchi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/#organization\",\"name\":\"Strada dei Parchi\",\"url\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/logo.png\",\"width\":290,\"height\":124,\"caption\":\"Strada dei Parchi\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stradadeiparchi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"west eagle | Strada dei Parchi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stradadeiparchi.it\/en\/tag\/west-eagle\/","og_locale":"en_US","og_type":"article","og_title":"west eagle | Strada dei Parchi","og_url":"https:\/\/www.stradadeiparchi.it\/en\/tag\/west-eagle\/","og_site_name":"Strada dei Parchi","twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.stradadeiparchi.it\/en\/tag\/west-eagle\/","url":"https:\/\/www.stradadeiparchi.it\/en\/tag\/west-eagle\/","name":"west eagle | Strada dei Parchi","isPartOf":{"@id":"https:\/\/www.stradadeiparchi.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.stradadeiparchi.it\/en\/tag\/west-eagle\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.stradadeiparchi.it\/en\/tag\/west-eagle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stradadeiparchi.it\/en\/"},{"@type":"ListItem","position":2,"name":"west eagle"}]},{"@type":"WebSite","@id":"https:\/\/www.stradadeiparchi.it\/#website","url":"https:\/\/www.stradadeiparchi.it\/","name":"Strada dei Parchi","description":"","publisher":{"@id":"https:\/\/www.stradadeiparchi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stradadeiparchi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.stradadeiparchi.it\/#organization","name":"Strada dei Parchi","url":"https:\/\/www.stradadeiparchi.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.stradadeiparchi.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.stradadeiparchi.it\/wp-content\/uploads\/2014\/10\/logo.png","contentUrl":"https:\/\/www.stradadeiparchi.it\/wp-content\/uploads\/2014\/10\/logo.png","width":290,"height":124,"caption":"Strada dei Parchi"},"image":{"@id":"https:\/\/www.stradadeiparchi.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.stradadeiparchi.it\/en\/wp-json\/wp\/v2\/tags\/5370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stradadeiparchi.it\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.stradadeiparchi.it\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.stradadeiparchi.it\/en\/wp-json\/wp\/v2\/posts?tags=5370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}